{"id":9302,"date":"2023-12-07T05:38:26","date_gmt":"2023-12-07T05:38:26","guid":{"rendered":"https:\/\/www.gradiant.com\/?p=9302"},"modified":"2025-11-26T11:54:14","modified_gmt":"2025-11-26T16:54:14","slug":"adio-e-gradiant-creano-una-partnership-per-la-sicurezza-idrica","status":"publish","type":"post","link":"https:\/\/www.gradiant.com\/it\/press-release\/adio-and-gradiant-forge-water-security-partnership\/","title":{"rendered":"L'Ufficio per gli investimenti di Abu Dhabi (ADIO) e Gradiant stringono una partnership per la sicurezza idrica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9302\" class=\"elementor elementor-9302\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a75c5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a75c5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c37abd2\" data-id=\"c37abd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236dfe0 elementor-widget elementor-widget-text-editor\" data-id=\"236dfe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Unendo le loro competenze e risorse, ADIO e Gradiant contribuiranno allo sviluppo e all'implementazione di soluzioni sostenibili che avranno un impatto positivo sulla sicurezza idrica della regione. L'accordo \u00e8 stato firmato durante la COP28, la Conferenza delle Nazioni Unite sui cambiamenti climatici.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4f5edf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4f5edf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06ddff6\" data-id=\"06ddff6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64b29a6 elementor-widget elementor-widget-text-editor\" data-id=\"64b29a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p>\n<p><strong>ABU DHABI, EAU - 7 dicembre 2023 -<\/strong>\u00a0La linea di prodotti <a href=\"https:\/\/www.investinabudhabi.ae\/\" target=\"_blank\" rel=\"noopener\">Ufficio investimenti di Abu Dhabi (ADIO)<\/a> ha annunciato oggi che <a href=\"https:\/\/www.gradiant.com\/it\/\" target=\"_blank\" rel=\"noopener\">Gradiant<\/a>ADIO, unicorno fondato dal MIT nel settore delle soluzioni per l'acqua e le acque reflue, ha scelto la capitale degli Emirati Arabi Uniti come sede del suo nuovo quartier generale EMEA e centro di innovazione globale. ADIO e Gradiant hanno firmato l'accordo di cooperazione durante la COP28, la Conferenza delle Nazioni Unite sui cambiamenti climatici, e l'azienda si \u00e8 unita al fiorente polo di innovatori di Abu Dhabi che guida lo sviluppo e la commercializzazione di soluzioni globali per i cambiamenti climatici.<\/p>\n<p>\u00a0<\/p>\n<p>ADIO sostiene la crescita dell'economia di Abu Dhabi attraendo aziende innovative in settori economici ad alta crescita allineati con la visione a lungo termine dell'Emirato. La collaborazione con Gradiant, che ha una valutazione di $1 mld, posiziona Abu Dhabi all'avanguardia in un settore in rapida crescita. Si prevede che il valore del mercato globale del trattamento delle acque e delle acque reflue raggiunger\u00e0 $1,1 tn entro il 2030.<\/p>\n<p>\u00a0<\/p>\n<p>ADIO fornir\u00e0 a Gradiant una gamma completa di supporti per la crescita e connessioni all'ecosistema di Abu Dhabi e alle opportunit\u00e0 commerciali internazionali. L'azienda con sede a Boston, che conta oltre 900 dipendenti in tutto il mondo, si trova in una posizione unica per affrontare le crescenti sfide idriche del mondo create dall'industrializzazione, dalla crescita demografica e dallo stress idrico. Le sue tecnologie consentono alle industrie pi\u00f9 importanti del mondo, tra cui i semiconduttori, i prodotti farmaceutici, gli alimenti e le bevande, le energie rinnovabili, la raffinazione e i prodotti chimici e l'energia, di ottimizzare le loro operazioni critiche e di ridurre la loro impronta idrica.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Badr Al-Olama, direttore generale di ADIO,<\/strong> ha dichiarato: \"L'aggiunta di un'azienda da un miliardo di dollari che gioca un ruolo attivo nel sostenere una priorit\u00e0 globale \u00e8 una spinta significativa all'ecosistema dell'innovazione e agli impegni net zero dell'Emirato. L'attenzione di Gradiant nel servire i clienti in settori chiave si allinea strettamente con le priorit\u00e0 economiche di Abu Dhabi e le sue operazioni nell'Emirato saranno un catalizzatore per la crescita in molti settori diversi\". Nell'ambito della sua pi\u00f9 ampia strategia di sicurezza idrica, gli Emirati Arabi Uniti stanno lavorando per aumentare il riutilizzo dell'acqua trattata, un obiettivo che ADIO \u00e8 orgogliosa di sostenere attraverso collaborazioni strategiche con importanti attori globali come Gradiant.\"<\/p>\n<p>\u00a0<\/p>\n<p>Gradiant offre soluzioni digitali e di processo per impianti idrici e di acque reflue e attualmente possiede circa 250 brevetti che coprono uno spettro di tecnologie. L'azienda riunisce uno stack tecnologico leader del settore con la potenza dell'intelligenza artificiale per soluzioni end-to-end alle sfide idriche pi\u00f9 importanti del mondo. Ha sviluppato un prodotto chiamato SmartOps per l'ottimizzazione delle prestazioni degli impianti e la gestione delle risorse dei sistemi di trattamento utilizzando l'apprendimento automatico e l'intelligenza artificiale.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Prakash Govindan, COO di Gradiant<\/strong>ha dichiarato: \"La nostra partnership con ADIO amplifica il nostro impegno nello sviluppo di soluzioni idriche sostenibili in tutta la regione EMEA. Facendo leva sul nostro comprovato successo a Singapore, puntiamo a posizionare Abu Dhabi e gli Emirati Arabi Uniti all'avanguardia nell'innovazione della tecnologia idrica. Il nostro approccio \u00e8 in linea con la Visione Economica 2030 di Abu Dhabi e siamo impegnati a migliorare la sicurezza idrica ed energetica della regione attraverso le nostre soluzioni all'avanguardia.\"<\/p>\n<p>\u00a0<\/p>\n<p>Il centro di innovazione globale di Gradiant ad Abu Dhabi svilupper\u00e0 e commercializzer\u00e0 nuove tecnologie per il trattamento delle acque. Lavorer\u00e0 inoltre a stretto contatto con l'Universit\u00e0 Khalifa, Masdar e le istituzioni accademiche locali per migliorare l'ecosistema dell'innovazione di Abu Dhabi. Queste partnership alimenteranno i progressi delle tecnologie RO Infinity e Carrier Gas Extraction (CGE) di Gradiant e altre soluzioni pionieristiche per il trattamento delle acque.<\/p>\n<p>\u00a0<\/p>\n<p>ADIO sta contribuendo allo sviluppo di soluzioni energetiche sostenibili ad Abu Dhabi, anche attraverso una collaborazione con Siemens Energy AG per stabilire il suo Customer Innovation Centre per il Medio Oriente nell'Emirato. Il centro \u00e8 uno dei quattro centri globali che accelereranno la commercializzazione di soluzioni innovative nel percorso verso il net zero negli EAU e a livello globale.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Informazioni su ADIO<\/strong><\/p>\n<p>L'Abu Dhabi Investment Office (ADIO) consente agli investitori locali, regionali e internazionali di prosperare e crescere nella capitale degli Emirati Arabi Uniti grazie alla stretta collaborazione con i partner governativi, gli investitori sovrani e i campioni nazionali. ADIO \u00e8 la principale piattaforma di Abu Dhabi che consente al settore privato di crescere, collaborare e competere a livello globale, fornendo l'accesso a opportunit\u00e0 di crescita, partnership strategiche e nuovi mercati in settori chiave che spaziano dall'immobiliare alle infrastrutture, dalle industrie all'agroalimentare, rafforzando l'investimento della nazione in talenti, innovazione e sostenibilit\u00e0. Con una rete crescente di uffici globali, gli investitori possono contattare ADIO visitando la sede centrale di Abu Dhabi o gli uffici internazionali di Pechino, Francoforte, Londra, New York, Parigi, San Francisco, Seoul e Tel Aviv. Visitate <a href=\"https:\/\/www.investinabudhabi.gov.ae\/\">Abu Dhabi Investment Office<\/a> per maggiori informazioni.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Informazioni su Gradiant<\/strong><\/p>\n<p>Gradiant is a Different Kind of Water Company. With a full suite of differentiated and proprietary end-to-end solutions for advanced water and wastewater treatment powered by the top minds in water, the company serves its clients&#8217; mission-critical operations in the world&#8217;s essential industries, including semiconductors, pharmaceuticals, food &amp; beverage, lithium and critical minerals, and renewable energy. Gradiant&#8217;s innovative solutions reduce water used and wastewater discharged, reclaim valuable resources, and renew wastewater into freshwater. The Boston-headquartered company was founded at MIT and has over 900 employees worldwide. Discover us at <a href=\"https:\/\/www.gradiant.com\/it\/\"><span class=\"s1\">gradiant.com.<\/span><\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>Contatto<\/strong><br \/>Felix Wang<br \/>Gradiant, vicepresidente del marketing<br \/>fwang@gradiant.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e5d10b0 e-flex e-con-boxed e-con e-parent\" data-id=\"e5d10b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fa3836 elementor-widget elementor-widget-html\" data-id=\"4fa3836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"http:\\\/\\\/schema.org\\\/\",\n    \"@type\": \"Article\",\n    \"headline\": \"ADIO and Gradiant Collaborate for Regional Water Security Solutions\",\n    \"author\": {\n        \"@type\": \"Person\",\n        \"name\": \"Nandu\"\n    },\n    \"publisher\": {\n        \"@type\": \"Organization\",\n        \"name\": \"Gradiant\",\n        \"logo\": {\n            \"@type\": \"ImageObject\",\n            \"url\": \"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Gradiant.svg\"\n        }\n    },\n    \"image\": \"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/ADIO-Gradiant-Newsroom.png\",\n    \"datePublished\": \"2023-12-07T05:38:26+00:00\",\n    \"dateModified\": \"2024-12-05T15:46:08+00:00\",\n    \"mainEntityOfPage\": {\n        \"@type\": \"WebPage\",\n        \"@id\": \"https:\\\/\\\/www.gradiant.com\\\/adio-and-gradiant-forge-water-security-partnership\\\/\"\n    },\n    \"description\": \"Gradiant and ADIO form a strategic partnership during COP28 to enhance water security in the Abu Dhabi region through innovative and sustainable solutions.\"\n}<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Unendo le loro competenze e risorse, ADIO e Gradiant contribuiranno allo sviluppo e all'implementazione di soluzioni sostenibili che avranno un impatto positivo sulla sicurezza idrica della regione. L'accordo \u00e8 stato firmato durante la COP28, la Conferenza delle Nazioni Unite sui cambiamenti climatici.<\/p>","protected":false},"author":14,"featured_media":10657,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[76,79,84],"class_list":["post-9302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-release","tag-industrial-wastewater-recycling","tag-minimum-zero-liquid-discharge","tag-business-momentum"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADIO and Gradiant Forge Partnership for Regional Water Security<\/title>\n<meta name=\"description\" content=\"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gradiant.com\/it\/comunicato-stampa\/adio-e-gradiant-creano-una-partnership-per-la-sicurezza-idrica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADIO and Gradiant Forge Partnership for Regional Water Security\" \/>\n<meta property=\"og:description\" content=\"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gradiant.com\/it\/comunicato-stampa\/adio-e-gradiant-creano-una-partnership-per-la-sicurezza-idrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradiant\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T05:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T16:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Nandu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Gradiant_Corp\" \/>\n<meta name=\"twitter:site\" content=\"@Gradiant_Corp\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nandu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/\"},\"author\":{\"name\":\"Nandu\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#\\\/schema\\\/person\\\/1496eb04a06a28e0d27a99858fa0e009\"},\"headline\":\"The Abu Dhabi Investment Office (ADIO) and Gradiant Forge Water Security Partnership\",\"datePublished\":\"2023-12-07T05:38:26+00:00\",\"dateModified\":\"2025-11-26T16:54:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/\"},\"wordCount\":862,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ADIO-Gradiant-Newsroom.webp\",\"keywords\":[\"Industrial Wastewater &amp; Recycling\",\"Minimum &amp; Zero Liquid Discharge\",\"Business Momentum\"],\"articleSection\":[\"Press Release\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/\",\"url\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/\",\"name\":\"ADIO and Gradiant Forge Partnership for Regional Water Security\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ADIO-Gradiant-Newsroom.webp\",\"datePublished\":\"2023-12-07T05:38:26+00:00\",\"dateModified\":\"2025-11-26T16:54:14+00:00\",\"description\":\"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ADIO-Gradiant-Newsroom.webp\",\"contentUrl\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ADIO-Gradiant-Newsroom.webp\",\"width\":1025,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/press-release\\\/adio-and-gradiant-forge-water-security-partnership\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Gradiant\",\"item\":\"https:\\\/\\\/www.gradiant.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Abu Dhabi Investment Office (ADIO) and Gradiant Forge Water Security Partnership\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gradiant.com\\\/\",\"name\":\"Gradiant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gradiant.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Corporation\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#organization\",\"name\":\"Gradiant\",\"legalName\":\"Gradiant Corporation\",\"url\":\"https:\\\/\\\/www.gradiant.com\\\/\",\"description\":\"Gradiant is a global water technology company that designs, builds, and operates advanced water and wastewater treatment systems for industrial clients. An MIT spinout founded in 2013, Gradiant helps companies reduce freshwater consumption, reclaim wastewater, and recover valuable resources through proprietary technologies achieving up to 99% water recovery.\",\"slogan\":\"Ensuring water for generations to come\",\"foundingDate\":\"2013\",\"foundingLocation\":{\"@type\":\"Place\",\"name\":\"Massachusetts Institute of Technology\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Cambridge\",\"addressRegion\":\"MA\",\"addressCountry\":\"US\"}},\"founder\":[{\"@type\":\"Person\",\"name\":\"Anurag Bajpayee\",\"jobTitle\":\"Chief Executive Officer\"},{\"@type\":\"Person\",\"name\":\"Prakash Govindan\",\"jobTitle\":\"Chief Operating Officer\"}],\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":1000,\"maxValue\":1500},\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"130 New Boston St, Suite 200\",\"addressLocality\":\"Woburn\",\"addressRegion\":\"MA\",\"postalCode\":\"01801\",\"addressCountry\":\"US\"},\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Gradiant.svg\",\"contentUrl\":\"https:\\\/\\\/www.gradiant.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Gradiant.svg\",\"width\":117,\"height\":26,\"caption\":\"Gradiant\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Gradiant_Corp\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gradiant-corporation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gradiantcorp\"],\"subOrganization\":[{\"@type\":\"Organization\",\"name\":\"alkaLi\",\"url\":\"https:\\\/\\\/alkali3.com\\\/\",\"description\":\"Gradiant spin-out company specializing in direct lithium extraction from produced water and brines using proprietary EC\u00b2 technology.\"},{\"@type\":\"Organization\",\"name\":\"Gradiant Energy Services\",\"description\":\"Gradiant subsidiary providing produced water treatment solutions for oil and gas operations.\"}],\"areaServed\":{\"@type\":\"Place\",\"name\":\"Worldwide\"},\"knowsAbout\":[\"Industrial water treatment\",\"Wastewater treatment\",\"Water recycling\",\"Desalination\",\"PFAS removal\",\"Ultrapure water\",\"Zero liquid discharge\",\"Direct lithium extraction\",\"Semiconductor water treatment\",\"Produced water treatment\"],\"award\":[\"Global Water Intelligence Water Technology Company of the Year 2024\",\"Global Water Intelligence Water Technology Company of the Year 2022\",\"TIME Best Inventions 2024\",\"Gold Edison Award 2025\",\"Global Cleantech 100 2023\"],\"naics\":\"221310\",\"isicV4\":\"3600\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gradiant.com\\\/#\\\/schema\\\/person\\\/1496eb04a06a28e0d27a99858fa0e009\",\"name\":\"Nandu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g\",\"caption\":\"Nandu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADIO and Gradiant Forge Partnership for Regional Water Security","description":"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gradiant.com\/it\/comunicato-stampa\/adio-e-gradiant-creano-una-partnership-per-la-sicurezza-idrica\/","og_locale":"it_IT","og_type":"article","og_title":"ADIO and Gradiant Forge Partnership for Regional Water Security","og_description":"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.","og_url":"https:\/\/www.gradiant.com\/it\/comunicato-stampa\/adio-e-gradiant-creano-una-partnership-per-la-sicurezza-idrica\/","og_site_name":"Gradiant","article_published_time":"2023-12-07T05:38:26+00:00","article_modified_time":"2025-11-26T16:54:14+00:00","og_image":[{"width":1025,"height":536,"url":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp","type":"image\/webp"}],"author":"Nandu","twitter_card":"summary_large_image","twitter_creator":"@Gradiant_Corp","twitter_site":"@Gradiant_Corp","twitter_misc":{"Scritto da":"Nandu","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#article","isPartOf":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/"},"author":{"name":"Nandu","@id":"https:\/\/www.gradiant.com\/#\/schema\/person\/1496eb04a06a28e0d27a99858fa0e009"},"headline":"The Abu Dhabi Investment Office (ADIO) and Gradiant Forge Water Security Partnership","datePublished":"2023-12-07T05:38:26+00:00","dateModified":"2025-11-26T16:54:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/"},"wordCount":862,"publisher":{"@id":"https:\/\/www.gradiant.com\/#organization"},"image":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp","keywords":["Industrial Wastewater &amp; Recycling","Minimum &amp; Zero Liquid Discharge","Business Momentum"],"articleSection":["Press Release"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/","url":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/","name":"ADIO and Gradiant Forge Partnership for Regional Water Security","isPartOf":{"@id":"https:\/\/www.gradiant.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#primaryimage"},"image":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp","datePublished":"2023-12-07T05:38:26+00:00","dateModified":"2025-11-26T16:54:14+00:00","description":"Gradiant and ADIO announce a partnership during COP28 to advance sustainable water security solutions in Abu Dhabi and the region.","breadcrumb":{"@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#primaryimage","url":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp","contentUrl":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2018\/07\/ADIO-Gradiant-Newsroom.webp","width":1025,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/www.gradiant.com\/press-release\/adio-and-gradiant-forge-water-security-partnership\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Gradiant","item":"https:\/\/www.gradiant.com\/"},{"@type":"ListItem","position":2,"name":"The Abu Dhabi Investment Office (ADIO) and Gradiant Forge Water Security Partnership"}]},{"@type":"WebSite","@id":"https:\/\/www.gradiant.com\/#website","url":"https:\/\/www.gradiant.com\/","name":"Gradiant","description":"","publisher":{"@id":"https:\/\/www.gradiant.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gradiant.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Corporation","@id":"https:\/\/www.gradiant.com\/#organization","name":"Gradiant","legalName":"Gradiant Corporation","url":"https:\/\/www.gradiant.com\/","description":"Gradiant is a global water technology company that designs, builds, and operates advanced water and wastewater treatment systems for industrial clients. An MIT spinout founded in 2013, Gradiant helps companies reduce freshwater consumption, reclaim wastewater, and recover valuable resources through proprietary technologies achieving up to 99% water recovery.","slogan":"Ensuring water for generations to come","foundingDate":"2013","foundingLocation":{"@type":"Place","name":"Massachusetts Institute of Technology","address":{"@type":"PostalAddress","addressLocality":"Cambridge","addressRegion":"MA","addressCountry":"US"}},"founder":[{"@type":"Person","name":"Anurag Bajpayee","jobTitle":"Chief Executive Officer"},{"@type":"Person","name":"Prakash Govindan","jobTitle":"Chief Operating Officer"}],"numberOfEmployees":{"@type":"QuantitativeValue","minValue":1000,"maxValue":1500},"address":{"@type":"PostalAddress","streetAddress":"130 New Boston St, Suite 200","addressLocality":"Woburn","addressRegion":"MA","postalCode":"01801","addressCountry":"US"},"logo":{"@type":"ImageObject","@id":"https:\/\/www.gradiant.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2023\/01\/Gradiant.svg","contentUrl":"https:\/\/www.gradiant.com\/wp-content\/uploads\/2023\/01\/Gradiant.svg","width":117,"height":26,"caption":"Gradiant"},"image":{"@id":"https:\/\/www.gradiant.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Gradiant_Corp","https:\/\/www.linkedin.com\/company\/gradiant-corporation\/","https:\/\/www.youtube.com\/@gradiantcorp"],"subOrganization":[{"@type":"Organization","name":"alkaLi","url":"https:\/\/alkali3.com\/","description":"Gradiant spin-out company specializing in direct lithium extraction from produced water and brines using proprietary EC\u00b2 technology."},{"@type":"Organization","name":"Gradiant Energy Services","description":"Gradiant subsidiary providing produced water treatment solutions for oil and gas operations."}],"areaServed":{"@type":"Place","name":"Worldwide"},"knowsAbout":["Industrial water treatment","Wastewater treatment","Water recycling","Desalination","PFAS removal","Ultrapure water","Zero liquid discharge","Direct lithium extraction","Semiconductor water treatment","Produced water treatment"],"award":["Global Water Intelligence Water Technology Company of the Year 2024","Global Water Intelligence Water Technology Company of the Year 2022","TIME Best Inventions 2024","Gold Edison Award 2025","Global Cleantech 100 2023"],"naics":"221310","isicV4":"3600"},{"@type":"Person","@id":"https:\/\/www.gradiant.com\/#\/schema\/person\/1496eb04a06a28e0d27a99858fa0e009","name":"Nand\u00f9","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66de06631094d025836b4e162c4644b06bfe22a0fa4b577abf2a50928bdac691?s=96&d=mm&r=g","caption":"Nandu"}}]}},"_links":{"self":[{"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/posts\/9302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/comments?post=9302"}],"version-history":[{"count":0,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/posts\/9302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/media\/10657"}],"wp:attachment":[{"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/media?parent=9302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/categories?post=9302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gradiant.com\/it\/wp-json\/wp\/v2\/tags?post=9302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}